{"id":12412,"date":"2020-01-24T10:15:36","date_gmt":"2020-01-24T10:15:36","guid":{"rendered":"https:\/\/seniorexpertcontact.org\/wp-content\/uploads\/3612_Wildeman_Nepal_2019_pic.jpg"},"modified":"2020-01-24T10:15:36","modified_gmt":"2020-01-24T10:15:36","slug":"3612_wildeman_nepal_2019_pic-2","status":"inherit","type":"attachment","link":"https:\/\/seniorexpertcontact.org\/en\/3612_wildeman_nepal_2019_pic-2\/","title":{"rendered":"3612_Wildeman_Nepal_2019_pic"},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-12412","attachment","type-attachment","status-inherit","hentry"],"aioseo_notices":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/seniorexpertcontact.org\/wp-content\/uploads\/3612_Wildeman_Nepal_2019_pic.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"492\" height=\"400\" src=\"https:\/\/seniorexpertcontact.org\/wp-content\/uploads\/3612_Wildeman_Nepal_2019_pic-492x400.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/seniorexpertcontact.org\/wp-content\/uploads\/3612_Wildeman_Nepal_2019_pic-492x400.jpg 492w, https:\/\/seniorexpertcontact.org\/wp-content\/uploads\/3612_Wildeman_Nepal_2019_pic-510x415.jpg 510w, https:\/\/seniorexpertcontact.org\/wp-content\/uploads\/3612_Wildeman_Nepal_2019_pic-737x600.jpg 737w, https:\/\/seniorexpertcontact.org\/wp-content\/uploads\/3612_Wildeman_Nepal_2019_pic-280x228.jpg 280w, https:\/\/seniorexpertcontact.org\/wp-content\/uploads\/3612_Wildeman_Nepal_2019_pic-768x625.jpg 768w, https:\/\/seniorexpertcontact.org\/wp-content\/uploads\/3612_Wildeman_Nepal_2019_pic-1536x1250.jpg 1536w, https:\/\/seniorexpertcontact.org\/wp-content\/uploads\/3612_Wildeman_Nepal_2019_pic-820x667.jpg 820w, https:\/\/seniorexpertcontact.org\/wp-content\/uploads\/3612_Wildeman_Nepal_2019_pic.jpg 1760w\" sizes=\"auto, (max-width: 492px) 100vw, 492px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1760,"height":1432,"file":"3612_Wildeman_Nepal_2019_pic.jpg","filesize":1485693,"sizes":{"woocommerce_thumbnail":{"file":"3612_Wildeman_Nepal_2019_pic-247x296.jpg","width":247,"height":296,"filesize":17316,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/seniorexpertcontact.org\/wp-content\/uploads\/3612_Wildeman_Nepal_2019_pic-247x296.jpg"},"woocommerce_gallery_thumbnail":{"file":"3612_Wildeman_Nepal_2019_pic-100x100.jpg","width":100,"height":100,"filesize":5578,"mime_type":"image\/jpeg","source_url":"https:\/\/seniorexpertcontact.org\/wp-content\/uploads\/3612_Wildeman_Nepal_2019_pic-100x100.jpg"},"woocommerce_single":{"file":"3612_Wildeman_Nepal_2019_pic-510x415.jpg","width":510,"height":415,"filesize":37364,"mime_type":"image\/jpeg","source_url":"https:\/\/seniorexpertcontact.org\/wp-content\/uploads\/3612_Wildeman_Nepal_2019_pic-510x415.jpg"},"medium":{"file":"3612_Wildeman_Nepal_2019_pic-492x400.jpg","width":492,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/seniorexpertcontact.org\/wp-content\/uploads\/3612_Wildeman_Nepal_2019_pic-492x400.jpg"},"large":{"file":"3612_Wildeman_Nepal_2019_pic-737x600.jpg","width":737,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/seniorexpertcontact.org\/wp-content\/uploads\/3612_Wildeman_Nepal_2019_pic-737x600.jpg"},"thumbnail":{"file":"3612_Wildeman_Nepal_2019_pic-280x228.jpg","width":280,"height":228,"mime_type":"image\/jpeg","source_url":"https:\/\/seniorexpertcontact.org\/wp-content\/uploads\/3612_Wildeman_Nepal_2019_pic-280x228.jpg"},"medium_large":{"file":"3612_Wildeman_Nepal_2019_pic-768x625.jpg","width":768,"height":625,"mime_type":"image\/jpeg","source_url":"https:\/\/seniorexpertcontact.org\/wp-content\/uploads\/3612_Wildeman_Nepal_2019_pic-768x625.jpg"},"ctl_avatar":{"file":"3612_Wildeman_Nepal_2019_pic-250x250.jpg","width":250,"height":250,"mime_type":"image\/jpeg","source_url":"https:\/\/seniorexpertcontact.org\/wp-content\/uploads\/3612_Wildeman_Nepal_2019_pic-250x250.jpg"},"1536x1536":{"file":"3612_Wildeman_Nepal_2019_pic-1536x1250.jpg","width":1536,"height":1250,"mime_type":"image\/jpeg","source_url":"https:\/\/seniorexpertcontact.org\/wp-content\/uploads\/3612_Wildeman_Nepal_2019_pic-1536x1250.jpg"},"shop_catalog":{"file":"3612_Wildeman_Nepal_2019_pic-280x210.jpg","width":280,"height":210,"mime_type":"image\/jpeg","source_url":"https:\/\/seniorexpertcontact.org\/wp-content\/uploads\/3612_Wildeman_Nepal_2019_pic-280x210.jpg"},"shop_single":{"file":"3612_Wildeman_Nepal_2019_pic-820x667.jpg","width":820,"height":667,"mime_type":"image\/jpeg","source_url":"https:\/\/seniorexpertcontact.org\/wp-content\/uploads\/3612_Wildeman_Nepal_2019_pic-820x667.jpg"},"shop_thumbnail":{"file":"3612_Wildeman_Nepal_2019_pic-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/seniorexpertcontact.org\/wp-content\/uploads\/3612_Wildeman_Nepal_2019_pic-100x100.jpg"},"full":{"file":"3612_Wildeman_Nepal_2019_pic.jpg","width":1760,"height":1432,"mime_type":"image\/jpeg","source_url":"https:\/\/seniorexpertcontact.org\/wp-content\/uploads\/3612_Wildeman_Nepal_2019_pic.jpg"}},"image_meta":{"aperture":"1.8","credit":"","camera":"iPhone 8 Plus","caption":"","created_timestamp":"1575627366","copyright":"","focal_length":"3.99","iso":"100","shutter_speed":"0.058823529411765","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/seniorexpertcontact.org\/wp-content\/uploads\/3612_Wildeman_Nepal_2019_pic.jpg","_links":{"self":[{"href":"https:\/\/seniorexpertcontact.org\/en\/wp-json\/wp\/v2\/media\/12412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seniorexpertcontact.org\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/seniorexpertcontact.org\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/seniorexpertcontact.org\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/seniorexpertcontact.org\/en\/wp-json\/wp\/v2\/comments?post=12412"}]}}